{"id":1664,"date":"2026-07-15T18:27:41","date_gmt":"2026-07-15T16:27:41","guid":{"rendered":"https:\/\/protestants-haguenau.fr\/?p=1664"},"modified":"2026-07-15T18:27:41","modified_gmt":"2026-07-15T16:27:41","slug":"il-y-a-toute-une-foret-dans-mon-coeur","status":"publish","type":"post","link":"https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/","title":{"rendered":"Il y a toute une for\u00eat dans mon c\u0153ur"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Il y a toute une for\u00eat dans mon c\u0153ur<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pr\u00e9dication&nbsp;du 12 juillet 2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Retour des enfants de la mini-colo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>En s&rsquo;appuyant sur le grand c\u0153ur r\u00e9alis\u00e9 par les enfants de la mini-colo, cette pr\u00e9dication m\u00e9dite sur nos joies, nos peurs, nos blessures et la pr\u00e9sence fid\u00e8le de Dieu au c\u0153ur de nos vies.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la mini-colo, chaque matin, il y a le \u00ab&nbsp;temps spi&nbsp;\u00bb. C\u2019est le moment o\u00f9 l\u2019on raconte une histoire biblique, o\u00f9 on prie et o\u00f9 on chante. Tout au long du s\u00e9jour, nous y avons r\u00e9alis\u00e9 une \u0153uvre pour s\u2019approprier notre th\u00e8me&nbsp;: \u00ab&nbsp;Il y a toute une for\u00eat dans mon c\u0153ur&nbsp;\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les enfants vont nous l\u2019apporter et nous allons le regarder ensemble.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"518\" src=\"https:\/\/protestants-haguenau.fr\/wp-content\/uploads\/2026\/07\/colo-1.jpg\" alt=\"\" class=\"wp-image-1666\" style=\"aspect-ratio:1.2355418514487913;width:426px;height:auto\" srcset=\"https:\/\/protestants-haguenau.fr\/wp-content\/uploads\/2026\/07\/colo-1.jpg 640w, https:\/\/protestants-haguenau.fr\/wp-content\/uploads\/2026\/07\/colo-1-300x243.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pendant quatre jours, ce grand c\u0153ur est rest\u00e9 affich\u00e9 dans notre salle. Au d\u00e9but de la semaine, il \u00e9tait presque vide. Puis, petit \u00e0 petit, nous l\u2019avons rempli avec des soleils, des nuages, des flammes, des arbres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais avant d&rsquo;\u00eatre un c\u0153ur rempli d&rsquo;\u00e9motions, ce c\u0153ur \u00e9tait d&rsquo;abord&#8230; une for\u00eat puisque c&rsquo;\u00e9tait le th\u00e8me de notre mini-colo : <strong>\u00ab Il y a toute une for\u00eat dans mon c\u0153ur. \u00bb<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pourquoi une for\u00eat ? Parce qu&rsquo;une for\u00eat n&rsquo;est jamais toute pareille. Il y a des clairi\u00e8res baign\u00e9es de lumi\u00e8re. Il y a des sous-bois o\u00f9 l&rsquo;on avance plus lentement. Il y a des ronces qui piquent, des foug\u00e8res immenses, des arbres centenaires et de toutes jeunes pousses. Il y a des oiseaux qui chantent, des chevreuils qui s&rsquo;enfuient, des ruisseaux qui murmurent. Il y a m\u00eame du bois mort&#8230; et pourtant ce bois mort est d\u00e9j\u00e0 plein de vie. Il nourrit les champignons, les insectes, la mousse. Il pr\u00e9pare d\u00e9j\u00e0 la for\u00eat de demain.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une for\u00eat n&rsquo;est pas parfaite. Une for\u00eat est vivante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et nous avons d\u00e9couvert cette semaine que notre c\u0153ur ressemble beaucoup plus \u00e0 une for\u00eat qu&rsquo;\u00e0 une maison bien rang\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les enfants ont \u00e9crit des petits papiers qu&rsquo;ils ont coll\u00e9s sur ce c\u0153ur. Je voudrais vous en lire quelques-uns&nbsp;: \u00ab&nbsp;Je suis joyeuse quand je vais \u00e0 la piscine&nbsp;\u00bb, \u00ab&nbsp;J\u2019ai peur des serpents&nbsp;\u00bb, \u00ab&nbsp;Je suis triste quand une personne de la famille meurt&nbsp;\u00bb, \u00ab&nbsp;Je suis en col\u00e8re quand quelqu\u2019un me casse quelque chose&nbsp;\u00bb, \u00ab&nbsp;Je suis sereine quand je m\u2019occupe de mon chien&nbsp;\u00bb, etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous voyez&#8230; Ce sont des morceaux de c\u0153ur que des enfants nous ont confi\u00e9s. Quel cadeau ils nous ont fait cette semaine ! Ils ont os\u00e9 nous montrer leur c\u0153ur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et je me suis demand\u00e9&#8230; si nous avions fait le m\u00eame exercice avec tous les adultes pr\u00e9sents ce matin, \u00e0 quoi ressemblerait notre grand c\u0153ur ? Quels papiers \u00e9cririons-nous ? Quelles joies ? Quelles peurs ? Quelles col\u00e8res ? Quelles tristesses ? Quelles paix retrouv\u00e9es ? Je crois que notre c\u0153ur ne serait pas si diff\u00e9rent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pendant la mini-colo, j&rsquo;ai appris une expression alsacienne que je ne connaissais pas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quand on appr\u00e9cie quelqu&rsquo;un tout de suite, on dit parfois : <em>\u00ab Sie isch mer uff&rsquo;s Herz gewachse. \u00bb <\/em>Litt\u00e9ralement : \u00ab Cette personne a pouss\u00e9 dans mon c\u0153ur. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je trouve cette image magnifique. On ne dit pas qu&rsquo;elle est entr\u00e9e dans mon c\u0153ur. On dit qu&rsquo;elle y a pouss\u00e9. Comme une plante. Comme un arbre. Comme si notre c\u0153ur \u00e9tait une terre vivante o\u00f9 quelque chose pouvait prendre racine et grandir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et c&rsquo;est exactement cela. Notre c\u0153ur n&rsquo;est pas un coffre o\u00f9 l&rsquo;on range des \u00e9motions. Notre c\u0153ur est vivant. Il y a des joies qui grandissent. Des peurs qui s&rsquo;apaisent. Des blessures qui cicatrisent.&nbsp; Des pardons qui demandent du temps. Des rencontres qui prennent racine en nous. Comme une for\u00eat, notre c\u0153ur traverse des saisons. Il y a des printemps o\u00f9 tout semble fleurir. Des automnes o\u00f9 il faut laisser tomber quelques feuilles. Des hivers o\u00f9 tout para\u00eet endormi. Et pourtant, m\u00eame en hiver, la for\u00eat continue de vivre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les deux histoires bibliques que nous avons entendues tout \u00e0 l&rsquo;heure nous racontent exactement cela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les disciples sont au milieu de la temp\u00eate. Ils ont peur. Ils pensent qu&rsquo;ils vont mourir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et J\u00e9sus ne leur dit pas : \u00ab Revenez me voir quand vous serez plus courageux. \u00bb Il est d\u00e9j\u00e0 dans leur barque. Il traverse la temp\u00eate avec eux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puis il y a \u00c9lie. Il est \u00e9puis\u00e9. Il n&rsquo;en peut plus. Il s&rsquo;endort sous un gen\u00eat et demande m\u00eame \u00e0 mourir. Et Dieu ne commence pas par lui faire un discours. Il lui donne \u00e0 manger. Il lui redonne des forces. Puis il le conduit jusqu&rsquo;\u00e0 l&rsquo;Horeb. Et l\u00e0, Dieu n&rsquo;est ni dans le vent qui arrache les montagnes, ni dans le tremblement de terre, ni dans le feu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est dans le souffle l\u00e9ger du silence.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans les deux r\u00e9cits, c&rsquo;est la m\u00eame bonne nouvelle. <strong>Dieu ne nous attend pas seulement dans les clairi\u00e8res. Quand tout va bien. Quand tout est lumineux. Dieu n&rsquo;a pas peur des sous-bois. Il n&rsquo;a pas peur des ronces. Il n&rsquo;a pas peur des temp\u00eates. Il vient nous rejoindre exactement l\u00e0 o\u00f9 nous sommes.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je voudrais revenir une derni\u00e8re fois sur ce grand c\u0153ur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jeudi matin, nous avons ajout\u00e9 des fils de scoubidous dor\u00e9s, la couleur qui symbolise Dieu parce que nous voulions dire quelque chose de lui.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Regardez. Il passe ici. Puis l\u00e0. Puis encore ici. Il traverse un soleil. Puis une flamme. Puis un nuage. Puis un panneau de danger. Puis un arbre. Comme si Dieu traversait toute notre for\u00eat. La joie. La peur. La col\u00e8re. La tristesse. La s\u00e9r\u00e9nit\u00e9. Comme si rien de tout cela ne lui \u00e9tait \u00e9tranger.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La foi ne consiste pas \u00e0 ne plus avoir peur. La foi ne consiste pas \u00e0 ne plus \u00eatre triste.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La foi ne consiste pas \u00e0 toujours sourire. La foi consiste \u00e0 d\u00e9couvrir que, dans chacune des saisons de notre vie, Dieu continue de marcher avec nous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et maintenant, ce c\u0153ur n&rsquo;est plus seulement celui des enfants de la mini-colo. Il devient le n\u00f4tre. Parce que chacun de nous porte une for\u00eat en lui. Les enfants. Les parents.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les grands-parents. Les personnes qui vivent seules. Celles qui viennent ici depuis toujours. Et celles qui poussent peut-\u00eatre aujourd&rsquo;hui la porte de cette \u00e9glise pour la premi\u00e8re fois depuis longtemps.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous connaissons tous des clairi\u00e8res o\u00f9 la lumi\u00e8re entre largement. Nous connaissons aussi des sous-bois o\u00f9 l&rsquo;on avance moins facilement. Et pourtant, une for\u00eat n&rsquo;est jamais belle parce qu&rsquo;elle est parfaite. Elle est belle parce qu&rsquo;elle est vivante. Il en est de m\u00eame de notre c\u0153ur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors, aujourd&rsquo;hui encore, le Christ nous dit la m\u00eame chose qu&rsquo;aux disciples dans la temp\u00eate et qu&rsquo;\u00e0 \u00c9lie sur la montagne : Je suis l\u00e0. Je ne quitte pas ta for\u00eat. J&rsquo;y habite.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors oui, <strong>il y a toute une for\u00eat dans mon c\u0153ur.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elle est parfois lumineuse. Parfois sombre. Parfois paisible. Parfois agit\u00e9e. Mais une chose demeure. <strong>Dieu habite l\u00e0, avec moi. <\/strong>Amen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sophie Jung, pasteure<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a toute une for\u00eat dans mon c\u0153ur Pr\u00e9dication&nbsp;du 12 juillet 2026 Retour des enfants de la mini-colo En s&rsquo;appuyant sur le grand c\u0153ur r\u00e9alis\u00e9 par les enfants de <a class=\"more-link\" href=\"https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/\">En savoir plus&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":1662,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[41],"tags":[],"class_list":["post-1664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ressources-spirituelles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il y a toute une for\u00eat dans mon c\u0153ur - Paroisse Protestante de Haguenau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il y a toute une for\u00eat dans mon c\u0153ur - Paroisse Protestante de Haguenau\" \/>\n<meta property=\"og:description\" content=\"Il y a toute une for\u00eat dans mon c\u0153ur Pr\u00e9dication&nbsp;du 12 juillet 2026 Retour des enfants de la mini-colo En s&rsquo;appuyant sur le grand c\u0153ur r\u00e9alis\u00e9 par les enfants de En savoir plus...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/\" \/>\n<meta property=\"og:site_name\" content=\"Paroisse Protestante de Haguenau\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/paroisseprotestantehaguenau\/?locale=fr_FR\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T16:27:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/protestants-haguenau.fr\/wp-content\/uploads\/2026\/07\/IMG_20260709_113431-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1928\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Secr\u00e9tariat Paroisse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Secr\u00e9tariat Paroisse\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/index.php\\\/2026\\\/07\\\/15\\\/il-y-a-toute-une-foret-dans-mon-coeur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/index.php\\\/2026\\\/07\\\/15\\\/il-y-a-toute-une-foret-dans-mon-coeur\\\/\"},\"author\":{\"name\":\"Secr\u00e9tariat Paroisse\",\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/#\\\/schema\\\/person\\\/3c2b6421387de263ef6a00f6352ce699\"},\"headline\":\"Il y a toute une for\u00eat dans mon c\u0153ur\",\"datePublished\":\"2026-07-15T16:27:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/index.php\\\/2026\\\/07\\\/15\\\/il-y-a-toute-une-foret-dans-mon-coeur\\\/\"},\"wordCount\":1273,\"publisher\":{\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/index.php\\\/2026\\\/07\\\/15\\\/il-y-a-toute-une-foret-dans-mon-coeur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/protestants-haguenau.fr\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG_20260709_113431-scaled.jpg\",\"articleSection\":[\"Ressources spirituelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/index.php\\\/2026\\\/07\\\/15\\\/il-y-a-toute-une-foret-dans-mon-coeur\\\/\",\"url\":\"https:\\\/\\\/protestants-haguenau.fr\\\/index.php\\\/2026\\\/07\\\/15\\\/il-y-a-toute-une-foret-dans-mon-coeur\\\/\",\"name\":\"Il y a toute une for\u00eat dans mon c\u0153ur - Paroisse Protestante de Haguenau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/index.php\\\/2026\\\/07\\\/15\\\/il-y-a-toute-une-foret-dans-mon-coeur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/index.php\\\/2026\\\/07\\\/15\\\/il-y-a-toute-une-foret-dans-mon-coeur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/protestants-haguenau.fr\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG_20260709_113431-scaled.jpg\",\"datePublished\":\"2026-07-15T16:27:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/index.php\\\/2026\\\/07\\\/15\\\/il-y-a-toute-une-foret-dans-mon-coeur\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/protestants-haguenau.fr\\\/index.php\\\/2026\\\/07\\\/15\\\/il-y-a-toute-une-foret-dans-mon-coeur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/index.php\\\/2026\\\/07\\\/15\\\/il-y-a-toute-une-foret-dans-mon-coeur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/protestants-haguenau.fr\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG_20260709_113431-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/protestants-haguenau.fr\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG_20260709_113431-scaled.jpg\",\"width\":2560,\"height\":1928},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/index.php\\\/2026\\\/07\\\/15\\\/il-y-a-toute-une-foret-dans-mon-coeur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/protestants-haguenau.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il y a toute une for\u00eat dans mon c\u0153ur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/#website\",\"url\":\"https:\\\/\\\/protestants-haguenau.fr\\\/\",\"name\":\"Paroisse Protestante de Haguenau\",\"description\":\"Actualit\u00e9s et informations\",\"publisher\":{\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/protestants-haguenau.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/#organization\",\"name\":\"Paroisse Protestante de Haguenau\",\"url\":\"https:\\\/\\\/protestants-haguenau.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/protestants-haguenau.fr\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-Plan-de-travail-5.png\",\"contentUrl\":\"https:\\\/\\\/protestants-haguenau.fr\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-Plan-de-travail-5.png\",\"width\":300,\"height\":138,\"caption\":\"Paroisse Protestante de Haguenau\"},\"image\":{\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/paroisseprotestantehaguenau\\\/?locale=fr_FR\",\"https:\\\/\\\/www.instagram.com\\\/paroisseprotestantehaguenau\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/protestants-haguenau.fr\\\/#\\\/schema\\\/person\\\/3c2b6421387de263ef6a00f6352ce699\",\"name\":\"Secr\u00e9tariat Paroisse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c6b5fd6022ed48641de841b1b44aee550f25d4679df263879e92151b981b3c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c6b5fd6022ed48641de841b1b44aee550f25d4679df263879e92151b981b3c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04c6b5fd6022ed48641de841b1b44aee550f25d4679df263879e92151b981b3c?s=96&d=mm&r=g\",\"caption\":\"Secr\u00e9tariat Paroisse\"},\"url\":\"https:\\\/\\\/protestants-haguenau.fr\\\/index.php\\\/author\\\/visiteur-provisoire\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il y a toute une for\u00eat dans mon c\u0153ur - Paroisse Protestante de Haguenau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/","og_locale":"fr_FR","og_type":"article","og_title":"Il y a toute une for\u00eat dans mon c\u0153ur - Paroisse Protestante de Haguenau","og_description":"Il y a toute une for\u00eat dans mon c\u0153ur Pr\u00e9dication&nbsp;du 12 juillet 2026 Retour des enfants de la mini-colo En s&rsquo;appuyant sur le grand c\u0153ur r\u00e9alis\u00e9 par les enfants de En savoir plus...","og_url":"https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/","og_site_name":"Paroisse Protestante de Haguenau","article_publisher":"https:\/\/www.facebook.com\/paroisseprotestantehaguenau\/?locale=fr_FR","article_published_time":"2026-07-15T16:27:41+00:00","og_image":[{"width":2560,"height":1928,"url":"https:\/\/protestants-haguenau.fr\/wp-content\/uploads\/2026\/07\/IMG_20260709_113431-scaled.jpg","type":"image\/jpeg"}],"author":"Secr\u00e9tariat Paroisse","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Secr\u00e9tariat Paroisse","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/#article","isPartOf":{"@id":"https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/"},"author":{"name":"Secr\u00e9tariat Paroisse","@id":"https:\/\/protestants-haguenau.fr\/#\/schema\/person\/3c2b6421387de263ef6a00f6352ce699"},"headline":"Il y a toute une for\u00eat dans mon c\u0153ur","datePublished":"2026-07-15T16:27:41+00:00","mainEntityOfPage":{"@id":"https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/"},"wordCount":1273,"publisher":{"@id":"https:\/\/protestants-haguenau.fr\/#organization"},"image":{"@id":"https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/#primaryimage"},"thumbnailUrl":"https:\/\/protestants-haguenau.fr\/wp-content\/uploads\/2026\/07\/IMG_20260709_113431-scaled.jpg","articleSection":["Ressources spirituelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/","url":"https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/","name":"Il y a toute une for\u00eat dans mon c\u0153ur - Paroisse Protestante de Haguenau","isPartOf":{"@id":"https:\/\/protestants-haguenau.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/#primaryimage"},"image":{"@id":"https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/#primaryimage"},"thumbnailUrl":"https:\/\/protestants-haguenau.fr\/wp-content\/uploads\/2026\/07\/IMG_20260709_113431-scaled.jpg","datePublished":"2026-07-15T16:27:41+00:00","breadcrumb":{"@id":"https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/#primaryimage","url":"https:\/\/protestants-haguenau.fr\/wp-content\/uploads\/2026\/07\/IMG_20260709_113431-scaled.jpg","contentUrl":"https:\/\/protestants-haguenau.fr\/wp-content\/uploads\/2026\/07\/IMG_20260709_113431-scaled.jpg","width":2560,"height":1928},{"@type":"BreadcrumbList","@id":"https:\/\/protestants-haguenau.fr\/index.php\/2026\/07\/15\/il-y-a-toute-une-foret-dans-mon-coeur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/protestants-haguenau.fr\/"},{"@type":"ListItem","position":2,"name":"Il y a toute une for\u00eat dans mon c\u0153ur"}]},{"@type":"WebSite","@id":"https:\/\/protestants-haguenau.fr\/#website","url":"https:\/\/protestants-haguenau.fr\/","name":"Paroisse Protestante de Haguenau","description":"Actualit\u00e9s et informations","publisher":{"@id":"https:\/\/protestants-haguenau.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/protestants-haguenau.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/protestants-haguenau.fr\/#organization","name":"Paroisse Protestante de Haguenau","url":"https:\/\/protestants-haguenau.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/protestants-haguenau.fr\/#\/schema\/logo\/image\/","url":"https:\/\/protestants-haguenau.fr\/wp-content\/uploads\/2025\/11\/cropped-Plan-de-travail-5.png","contentUrl":"https:\/\/protestants-haguenau.fr\/wp-content\/uploads\/2025\/11\/cropped-Plan-de-travail-5.png","width":300,"height":138,"caption":"Paroisse Protestante de Haguenau"},"image":{"@id":"https:\/\/protestants-haguenau.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/paroisseprotestantehaguenau\/?locale=fr_FR","https:\/\/www.instagram.com\/paroisseprotestantehaguenau\/"]},{"@type":"Person","@id":"https:\/\/protestants-haguenau.fr\/#\/schema\/person\/3c2b6421387de263ef6a00f6352ce699","name":"Secr\u00e9tariat Paroisse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/04c6b5fd6022ed48641de841b1b44aee550f25d4679df263879e92151b981b3c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04c6b5fd6022ed48641de841b1b44aee550f25d4679df263879e92151b981b3c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04c6b5fd6022ed48641de841b1b44aee550f25d4679df263879e92151b981b3c?s=96&d=mm&r=g","caption":"Secr\u00e9tariat Paroisse"},"url":"https:\/\/protestants-haguenau.fr\/index.php\/author\/visiteur-provisoire\/"}]}},"_links":{"self":[{"href":"https:\/\/protestants-haguenau.fr\/index.php\/wp-json\/wp\/v2\/posts\/1664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/protestants-haguenau.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/protestants-haguenau.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/protestants-haguenau.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/protestants-haguenau.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1664"}],"version-history":[{"count":1,"href":"https:\/\/protestants-haguenau.fr\/index.php\/wp-json\/wp\/v2\/posts\/1664\/revisions"}],"predecessor-version":[{"id":1667,"href":"https:\/\/protestants-haguenau.fr\/index.php\/wp-json\/wp\/v2\/posts\/1664\/revisions\/1667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/protestants-haguenau.fr\/index.php\/wp-json\/wp\/v2\/media\/1662"}],"wp:attachment":[{"href":"https:\/\/protestants-haguenau.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/protestants-haguenau.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/protestants-haguenau.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}